{"id":2034,"date":"2021-09-24T11:16:17","date_gmt":"2021-09-24T14:16:17","guid":{"rendered":"https:\/\/www.wtsoftware.com.br\/news\/?p=2034"},"modified":"2023-02-11T11:17:55","modified_gmt":"2023-02-11T14:17:55","slug":"espiao-que-monitora-o-whatsapp","status":"publish","type":"post","link":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/","title":{"rendered":"Espi\u00e3o que monitora o WhatsApp"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><meta charset=\"utf-8\">Espi\u00e3o que monitora o WhatsApp \u00e9 uma d\u00e1diva que n\u00f3s da <a href=\"https:\/\/www.wtsoftware.com.br\/\">Wt Software<\/a> conseguimos desenvolver ao longo de 12 anos. Entretanto, n\u00f3s estamos aprimorando e melhorando nosso aplicativo, veja a seguir: Espi\u00e3o que monitora o WhatsApp.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.wtsoftware.com.br\/news\/wp-content\/uploads\/2020\/08\/logo2-1024x427.png\" alt=\"app de espionar whatsapp\"\/><\/figure>\n\n\n\n<div class=\"wp-block-button aligncenter is-style-squared\">\n\n<a class=\"button_purple\" href=\"https:\/\/wtsoftware.com.br\/download-wspy-mobile.html\">Instalar gr\u00e1tis<\/a>\n<a class=\"button_green\" href=\"https:\/\/wtsoftware.com.br\/wspy-planos.html\">Ver Planos<\/a>\n\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><meta charset=\"utf-8\"><meta charset=\"utf-8\">Descubra como funciona espi\u00e3o que monitora o WhatsApp<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 de extrema import\u00e2ncia entender que este \u00e9 apenas um termo de pesquisa, pois quando de clonagem de WhatsApp, estamos querendo tratar da mesma coisa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por mais que este m\u00e9todo tenha diversas formas de ser chamado, se trata de um aplicativo espi\u00e3o de celular, que deve ser baixado no celular da pessoa que voc\u00ea pretende monitorar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma vez que monitorar uma pessoa sem o devido consentimento \u00e9 ilegal, assim como qualquer tipo de invas\u00e3o em dispositivos eletr\u00f4nicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Muitas pessoas ainda caem em diversos golpes tentando localizar um celular roubado ou perdido, pois acham que pode ser poss\u00edvel localiza-lo apenas com o n\u00famero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este \u00e9 o tipo de golpe mais comum no (sociedade), entre tantos outros. Mas podemos garantir que qualquer tipo de procedimento como este \u00e9 uma completa farsa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lembrando tamb\u00e9m que por meio destes servi\u00e7os ilegais, pois tanto os seus dados pessoais quanto os da pessoa que voc\u00ea pretende monitorar ficam completamente vulner\u00e1veis<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><meta charset=\"utf-8\">Escolha wSpy pro!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O espi\u00e3o de celular android ou <a href=\"https:\/\/espiao.app\/\">wSpy pro <\/a>\u00e9 um programa de monitoramento remoto, que observa grandes a\u00e7\u00f5es feitas no celular do alvo, entretanto, dever\u00e1 baix\u00e1-lo no celular do alvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, nosso espi\u00e3o de celular wSpy pro captura todas as mensagens escritas e \u00e1udios do celular alvo, e s\u00e3o enviadas para o painel de controle, onde consegue visualizar as atividades suspeitas do alvo.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li> Localiza\u00e7\u00e3o do aparelho (GPS)<\/li>\n\n\n\n<li>SMS (enviados e recebidos no celular)<\/li>\n\n\n\n<li>Lista de contatos salvos no celular, com nome e n\u00famero<\/li>\n\n\n\n<li>Registro de chamadas (nome, n\u00famero, dura\u00e7\u00e3o, data, hor\u00e1rio e status da chamada)<\/li>\n\n\n\n<li>Conversas e \u00e1udios do WhatsApp (enviadas e recebidas)<\/li>\n\n\n\n<li>Conversas do Instagram (enviadas e recebidas)<\/li>\n\n\n\n<li>Fotografa o ambiente do aparelho<\/li>\n\n\n\n<li>Sites acessados e pesquisas online (Google)<\/li>\n\n\n\n<li>Teclas digitadas<\/li>\n\n\n\n<li>Escuta ambiente<\/li>\n\n\n\n<li>Fotos da galeria<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"INSTALANDO UM APP ESPI\u00c3O INVIS\u00cdVEL! (Veja como fazer da maneira certa)\" width=\"700\" height=\"394\" src=\"https:\/\/www.youtube.com\/embed\/gy9G-zLyUaU?start=31&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Espi\u00e3o que monitora o WhatsApp \u00e9 uma d\u00e1diva que n\u00f3s da Wt Software conseguimos desenvolver ao longo de 12 anos. Entretanto, n\u00f3s estamos aprimorando e melhorando nosso aplicativo, veja a seguir: Espi\u00e3o que monitora o WhatsApp. Instalar gr\u00e1tis Ver Planos Descubra como funciona espi\u00e3o que monitora o WhatsApp \u00c9 de extrema import\u00e2ncia entender que este [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[61,43,101,127,71,128],"class_list":["post-2034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contatos","tag-clonar-whatsapp","tag-espiao-de-whatsapp","tag-monitoramento-de-celular","tag-top5","tag-whatsapp-espiao","tag-world"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espi\u00e3o que monitora o WhatsApp - WT Software<\/title>\n<meta name=\"description\" content=\"Mostraremos como espionar um celular e o WhatsApp, veja no artigo abaixo: Espi\u00e3o que monitora o WhatsApp\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espi\u00e3o que monitora o WhatsApp - WT Software\" \/>\n<meta property=\"og:description\" content=\"Mostraremos como espionar um celular e o WhatsApp, veja no artigo abaixo: Espi\u00e3o que monitora o WhatsApp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/\" \/>\n<meta property=\"og:site_name\" content=\"WT Software\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wspypro\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-24T14:16:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-11T14:17:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wtsoftware.com.br\/news\/wp-content\/uploads\/2019\/10\/whatsapp-espiao-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adilson Junior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adilson Junior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/\"},\"author\":{\"name\":\"Adilson Junior\",\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/#\\\/schema\\\/person\\\/f20c64952b8814ac63c6da4c43e439d5\"},\"headline\":\"Espi\u00e3o que monitora o WhatsApp\",\"datePublished\":\"2021-09-24T14:16:17+00:00\",\"dateModified\":\"2023-02-11T14:17:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/\"},\"wordCount\":368,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/whatsapp-espiao-2.jpg\",\"keywords\":[\"clonar whatsapp\",\"espiao de whatsapp\",\"Monitoramento de celular\",\"top5\",\"whatsapp espiao\",\"World\"],\"articleSection\":[\"Contatos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/\",\"url\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/\",\"name\":\"Espi\u00e3o que monitora o WhatsApp - WT Software\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/whatsapp-espiao-2.jpg\",\"datePublished\":\"2021-09-24T14:16:17+00:00\",\"dateModified\":\"2023-02-11T14:17:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/#\\\/schema\\\/person\\\/f20c64952b8814ac63c6da4c43e439d5\"},\"description\":\"Mostraremos como espionar um celular e o WhatsApp, veja no artigo abaixo: Espi\u00e3o que monitora o WhatsApp\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/whatsapp-espiao-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/whatsapp-espiao-2.jpg\",\"width\":800,\"height\":480,\"caption\":\"Hackear WhatsApp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/contatos\\\/espiao-que-monitora-o-whatsapp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espi\u00e3o que monitora o WhatsApp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/\",\"name\":\"WT Software\",\"description\":\"Programa espi\u00e3o de monitoramento e controle parental.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/#\\\/schema\\\/person\\\/f20c64952b8814ac63c6da4c43e439d5\",\"name\":\"Adilson Junior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac72a0d1e1d87dcf56f67d3f1cf22abf323a08d47838e8cbe58455f53ebf4b2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac72a0d1e1d87dcf56f67d3f1cf22abf323a08d47838e8cbe58455f53ebf4b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac72a0d1e1d87dcf56f67d3f1cf22abf323a08d47838e8cbe58455f53ebf4b2?s=96&d=mm&r=g\",\"caption\":\"Adilson Junior\"},\"url\":\"https:\\\/\\\/www.wtsoftware.com.br\\\/news\\\/author\\\/adilson-junior\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espi\u00e3o que monitora o WhatsApp - WT Software","description":"Mostraremos como espionar um celular e o WhatsApp, veja no artigo abaixo: Espi\u00e3o que monitora o WhatsApp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/","og_locale":"pt_BR","og_type":"article","og_title":"Espi\u00e3o que monitora o WhatsApp - WT Software","og_description":"Mostraremos como espionar um celular e o WhatsApp, veja no artigo abaixo: Espi\u00e3o que monitora o WhatsApp","og_url":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/","og_site_name":"WT Software","article_publisher":"https:\/\/www.facebook.com\/wspypro","article_published_time":"2021-09-24T14:16:17+00:00","article_modified_time":"2023-02-11T14:17:55+00:00","og_image":[{"width":800,"height":480,"url":"https:\/\/www.wtsoftware.com.br\/news\/wp-content\/uploads\/2019\/10\/whatsapp-espiao-2.jpg","type":"image\/jpeg"}],"author":"Adilson Junior","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Adilson Junior","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/#article","isPartOf":{"@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/"},"author":{"name":"Adilson Junior","@id":"https:\/\/www.wtsoftware.com.br\/news\/#\/schema\/person\/f20c64952b8814ac63c6da4c43e439d5"},"headline":"Espi\u00e3o que monitora o WhatsApp","datePublished":"2021-09-24T14:16:17+00:00","dateModified":"2023-02-11T14:17:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/"},"wordCount":368,"commentCount":0,"image":{"@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wtsoftware.com.br\/news\/wp-content\/uploads\/2019\/10\/whatsapp-espiao-2.jpg","keywords":["clonar whatsapp","espiao de whatsapp","Monitoramento de celular","top5","whatsapp espiao","World"],"articleSection":["Contatos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/","url":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/","name":"Espi\u00e3o que monitora o WhatsApp - WT Software","isPartOf":{"@id":"https:\/\/www.wtsoftware.com.br\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/#primaryimage"},"image":{"@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wtsoftware.com.br\/news\/wp-content\/uploads\/2019\/10\/whatsapp-espiao-2.jpg","datePublished":"2021-09-24T14:16:17+00:00","dateModified":"2023-02-11T14:17:55+00:00","author":{"@id":"https:\/\/www.wtsoftware.com.br\/news\/#\/schema\/person\/f20c64952b8814ac63c6da4c43e439d5"},"description":"Mostraremos como espionar um celular e o WhatsApp, veja no artigo abaixo: Espi\u00e3o que monitora o WhatsApp","breadcrumb":{"@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/#primaryimage","url":"https:\/\/www.wtsoftware.com.br\/news\/wp-content\/uploads\/2019\/10\/whatsapp-espiao-2.jpg","contentUrl":"https:\/\/www.wtsoftware.com.br\/news\/wp-content\/uploads\/2019\/10\/whatsapp-espiao-2.jpg","width":800,"height":480,"caption":"Hackear WhatsApp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wtsoftware.com.br\/news\/contatos\/espiao-que-monitora-o-whatsapp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.wtsoftware.com.br\/news\/"},{"@type":"ListItem","position":2,"name":"Espi\u00e3o que monitora o WhatsApp"}]},{"@type":"WebSite","@id":"https:\/\/www.wtsoftware.com.br\/news\/#website","url":"https:\/\/www.wtsoftware.com.br\/news\/","name":"WT Software","description":"Programa espi\u00e3o de monitoramento e controle parental.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wtsoftware.com.br\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.wtsoftware.com.br\/news\/#\/schema\/person\/f20c64952b8814ac63c6da4c43e439d5","name":"Adilson Junior","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/aac72a0d1e1d87dcf56f67d3f1cf22abf323a08d47838e8cbe58455f53ebf4b2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aac72a0d1e1d87dcf56f67d3f1cf22abf323a08d47838e8cbe58455f53ebf4b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac72a0d1e1d87dcf56f67d3f1cf22abf323a08d47838e8cbe58455f53ebf4b2?s=96&d=mm&r=g","caption":"Adilson Junior"},"url":"https:\/\/www.wtsoftware.com.br\/news\/author\/adilson-junior\/"}]}},"_links":{"self":[{"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/posts\/2034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/comments?post=2034"}],"version-history":[{"count":3,"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/posts\/2034\/revisions"}],"predecessor-version":[{"id":3061,"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/posts\/2034\/revisions\/3061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/media\/544"}],"wp:attachment":[{"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/media?parent=2034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/categories?post=2034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wtsoftware.com.br\/news\/wp-json\/wp\/v2\/tags?post=2034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}